{"id":17150,"count":15,"description":"","link":"https:\/\/lebouquet.brstdev.com\/en\/best-seller\/","name":"Best Seller","slug":"best-seller","taxonomy":"product_cat","parent":7553,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/lebouquet.brstdev.com\/en\/wp-json\/wp\/v2\/product_cat\/17150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lebouquet.brstdev.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lebouquet.brstdev.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/lebouquet.brstdev.com\/en\/wp-json\/wp\/v2\/product_cat\/7553"}],"wp:post_type":[{"href":"https:\/\/lebouquet.brstdev.com\/en\/wp-json\/wp\/v2\/product?product_cat=17150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}